{"id":12634,"date":"2026-05-13T14:25:52","date_gmt":"2026-05-13T12:25:52","guid":{"rendered":"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/"},"modified":"2026-05-13T14:25:57","modified_gmt":"2026-05-13T12:25:57","slug":"sopletes","status":"publish","type":"product","link":"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/","title":{"rendered":"SOPLETES"},"content":{"rendered":"<p>Soplete para soldadura de l\u00e1minas asf\u00e1lticas, incluyendo manguera flexible de 10 m de longitud y conexi\u00f3n a bombona de propano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soplete con manguera de 10 m de longitud<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"family":[3076],"product_notice":[12157],"product_icon":[],"product_application":[],"product_standards_certification":[],"product_benefits":[],"product_support":[],"product_substrate_preparation":[],"product_important_indications":[],"product_conservation":[],"product_warning":[],"product_safety_hygiene":[],"system_certification":[],"product_maintenance":[],"product_safety_datasheet":[],"filter_special_uses":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Soplete peque\u00f1o para soldar tela asf\u00e1ltica con manguera flexible<\/title>\n<meta name=\"description\" content=\"Soplete peque\u00f1o para soldadura de l\u00e1minas asf\u00e1lticas, incluyendo manguera flexible de 10 m de longitud y conexi\u00f3n a bombona de propano. Top ventas. Danosa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soplete peque\u00f1o para soldar tela asf\u00e1ltica con manguera flexible\" \/>\n<meta property=\"og:description\" content=\"Soplete peque\u00f1o para soldadura de l\u00e1minas asf\u00e1lticas, incluyendo manguera flexible de 10 m de longitud y conexi\u00f3n a bombona de propano. Top ventas. Danosa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/\" \/>\n<meta property=\"og:site_name\" content=\"Danosa | Soluciones para la construcci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aislamientoeimpermeabilizacion\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T12:25:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DANOSA_SPAIN\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/#website\",\"url\":\"https:\/\/www.danosa.com\/es-es\/\",\"name\":\"Danosa | Soluciones para la construcci\u00f3n\",\"description\":\"Impermeabilizaci\u00f3n, aislamiento ac\u00fastico y t\u00e9rmico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.danosa.com\/es-es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/#webpage\",\"url\":\"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/\",\"name\":\"Soplete peque\u00f1o para soldar tela asf\u00e1ltica con manguera flexible\",\"isPartOf\":{\"@id\":\"https:\/\/www.danosa.com\/es-es\/#website\"},\"datePublished\":\"2026-05-13T12:25:52+00:00\",\"dateModified\":\"2026-05-13T12:25:57+00:00\",\"description\":\"Soplete peque\u00f1o para soldadura de l\u00e1minas asf\u00e1lticas, incluyendo manguera flexible de 10 m de longitud y conexi\u00f3n a bombona de propano. Top ventas. Danosa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.danosa.com\/es-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SOPLETES\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soplete peque\u00f1o para soldar tela asf\u00e1ltica con manguera flexible","description":"Soplete peque\u00f1o para soldadura de l\u00e1minas asf\u00e1lticas, incluyendo manguera flexible de 10 m de longitud y conexi\u00f3n a bombona de propano. Top ventas. Danosa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/","og_locale":"es_ES","og_type":"article","og_title":"Soplete peque\u00f1o para soldar tela asf\u00e1ltica con manguera flexible","og_description":"Soplete peque\u00f1o para soldadura de l\u00e1minas asf\u00e1lticas, incluyendo manguera flexible de 10 m de longitud y conexi\u00f3n a bombona de propano. Top ventas. Danosa.","og_url":"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/","og_site_name":"Danosa | Soluciones para la construcci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/aislamientoeimpermeabilizacion\/","article_modified_time":"2026-05-13T12:25:57+00:00","twitter_card":"summary_large_image","twitter_site":"@DANOSA_SPAIN","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.danosa.com\/es-es\/#website","url":"https:\/\/www.danosa.com\/es-es\/","name":"Danosa | Soluciones para la construcci\u00f3n","description":"Impermeabilizaci\u00f3n, aislamiento ac\u00fastico y t\u00e9rmico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.danosa.com\/es-es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/#webpage","url":"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/","name":"Soplete peque\u00f1o para soldar tela asf\u00e1ltica con manguera flexible","isPartOf":{"@id":"https:\/\/www.danosa.com\/es-es\/#website"},"datePublished":"2026-05-13T12:25:52+00:00","dateModified":"2026-05-13T12:25:57+00:00","description":"Soplete peque\u00f1o para soldadura de l\u00e1minas asf\u00e1lticas, incluyendo manguera flexible de 10 m de longitud y conexi\u00f3n a bombona de propano. Top ventas. Danosa.","breadcrumb":{"@id":"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.danosa.com\/es-es\/producto\/sopletes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.danosa.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"SOPLETES"}]}]}},"_links":{"self":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product\/12634"}],"collection":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/media?parent=12634"}],"wp:term":[{"taxonomy":"family","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/family?post=12634"},{"taxonomy":"product_notice","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_notice?post=12634"},{"taxonomy":"product_icon","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_icon?post=12634"},{"taxonomy":"product_application","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_application?post=12634"},{"taxonomy":"product_standards_certification","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_standards_certification?post=12634"},{"taxonomy":"product_benefits","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_benefits?post=12634"},{"taxonomy":"product_support","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_support?post=12634"},{"taxonomy":"product_substrate_preparation","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_substrate_preparation?post=12634"},{"taxonomy":"product_important_indications","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_important_indications?post=12634"},{"taxonomy":"product_conservation","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_conservation?post=12634"},{"taxonomy":"product_warning","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_warning?post=12634"},{"taxonomy":"product_safety_hygiene","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_safety_hygiene?post=12634"},{"taxonomy":"system_certification","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/system_certification?post=12634"},{"taxonomy":"product_maintenance","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_maintenance?post=12634"},{"taxonomy":"product_safety_datasheet","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_safety_datasheet?post=12634"},{"taxonomy":"filter_special_uses","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/filter_special_uses?post=12634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}