{"id":14509,"date":"2026-05-13T02:30:18","date_gmt":"2026-05-13T00:30:18","guid":{"rendered":"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/"},"modified":"2026-05-13T02:30:21","modified_gmt":"2026-05-13T00:30:21","slug":"nexalon-perfil-colaminado-a","status":"publish","type":"product","link":"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/","title":{"rendered":"NEXALON PERFIL COLAMINADO A"},"content":{"rendered":"<p>Perfil de chapa colaminada con TPO, utilizado como remate de la impermeabilizaci\u00f3n tanto en el plano horizontal como en el paramento vertical.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Perfil de chapa colaminada con TPO<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"family":[3073],"product_notice":[12157],"product_icon":[],"product_application":[11129],"product_standards_certification":[],"product_benefits":[13898,10322,10515,10552],"product_support":[],"product_substrate_preparation":[],"product_important_indications":[],"product_conservation":[11555,11563,11591,11595,11640,13902,11660,14354,14355,11718,11719,11721],"product_warning":[],"product_safety_hygiene":[],"system_certification":[3271,3272],"product_maintenance":[],"product_safety_datasheet":[],"filter_special_uses":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Perfil COLAMINADO plano de PVC - A | Remate para impermeabilizaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Perfil de chapa colaminada con PVC-p para remate de la impermeabilizaci\u00f3n tanto en el plano horizontal como en el paramento vertical. Garant\u00eda Danosa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perfil COLAMINADO plano de PVC - A | Remate para impermeabilizaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Perfil de chapa colaminada con PVC-p para remate de la impermeabilizaci\u00f3n tanto en el plano horizontal como en el paramento vertical. Garant\u00eda Danosa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Danosa | Soluciones para la construcci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aislamientoeimpermeabilizacion\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T00:30:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DANOSA_SPAIN\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/#website\",\"url\":\"https:\/\/www.danosa.com\/es-es\/\",\"name\":\"Danosa | Soluciones para la construcci\u00f3n\",\"description\":\"Impermeabilizaci\u00f3n, aislamiento ac\u00fastico y t\u00e9rmico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.danosa.com\/es-es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/#webpage\",\"url\":\"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/\",\"name\":\"Perfil COLAMINADO plano de PVC - A | Remate para impermeabilizaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.danosa.com\/es-es\/#website\"},\"datePublished\":\"2026-05-13T00:30:18+00:00\",\"dateModified\":\"2026-05-13T00:30:21+00:00\",\"description\":\"Perfil de chapa colaminada con PVC-p para remate de la impermeabilizaci\u00f3n tanto en el plano horizontal como en el paramento vertical. Garant\u00eda Danosa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.danosa.com\/es-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NEXALON PERFIL COLAMINADO A\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perfil COLAMINADO plano de PVC - A | Remate para impermeabilizaci\u00f3n","description":"Perfil de chapa colaminada con PVC-p para remate de la impermeabilizaci\u00f3n tanto en el plano horizontal como en el paramento vertical. Garant\u00eda Danosa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/","og_locale":"es_ES","og_type":"article","og_title":"Perfil COLAMINADO plano de PVC - A | Remate para impermeabilizaci\u00f3n","og_description":"Perfil de chapa colaminada con PVC-p para remate de la impermeabilizaci\u00f3n tanto en el plano horizontal como en el paramento vertical. Garant\u00eda Danosa.","og_url":"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/","og_site_name":"Danosa | Soluciones para la construcci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/aislamientoeimpermeabilizacion\/","article_modified_time":"2026-05-13T00:30:21+00:00","twitter_card":"summary_large_image","twitter_site":"@DANOSA_SPAIN","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.danosa.com\/es-es\/#website","url":"https:\/\/www.danosa.com\/es-es\/","name":"Danosa | Soluciones para la construcci\u00f3n","description":"Impermeabilizaci\u00f3n, aislamiento ac\u00fastico y t\u00e9rmico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.danosa.com\/es-es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/#webpage","url":"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/","name":"Perfil COLAMINADO plano de PVC - A | Remate para impermeabilizaci\u00f3n","isPartOf":{"@id":"https:\/\/www.danosa.com\/es-es\/#website"},"datePublished":"2026-05-13T00:30:18+00:00","dateModified":"2026-05-13T00:30:21+00:00","description":"Perfil de chapa colaminada con PVC-p para remate de la impermeabilizaci\u00f3n tanto en el plano horizontal como en el paramento vertical. Garant\u00eda Danosa.","breadcrumb":{"@id":"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.danosa.com\/es-es\/producto\/nexalon-perfil-colaminado-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.danosa.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"NEXALON PERFIL COLAMINADO A"}]}]}},"_links":{"self":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product\/14509"}],"collection":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/media?parent=14509"}],"wp:term":[{"taxonomy":"family","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/family?post=14509"},{"taxonomy":"product_notice","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_notice?post=14509"},{"taxonomy":"product_icon","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_icon?post=14509"},{"taxonomy":"product_application","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_application?post=14509"},{"taxonomy":"product_standards_certification","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_standards_certification?post=14509"},{"taxonomy":"product_benefits","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_benefits?post=14509"},{"taxonomy":"product_support","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_support?post=14509"},{"taxonomy":"product_substrate_preparation","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_substrate_preparation?post=14509"},{"taxonomy":"product_important_indications","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_important_indications?post=14509"},{"taxonomy":"product_conservation","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_conservation?post=14509"},{"taxonomy":"product_warning","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_warning?post=14509"},{"taxonomy":"product_safety_hygiene","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_safety_hygiene?post=14509"},{"taxonomy":"system_certification","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/system_certification?post=14509"},{"taxonomy":"product_maintenance","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_maintenance?post=14509"},{"taxonomy":"product_safety_datasheet","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_safety_datasheet?post=14509"},{"taxonomy":"filter_special_uses","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/filter_special_uses?post=14509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}