{"id":3986,"date":"2026-05-13T02:21:14","date_gmt":"2026-05-13T00:21:14","guid":{"rendered":"https:\/\/www.danosa.com\/es-es\/blog\/product\/danopol-hs-1-5-coverstrip\/"},"modified":"2026-05-13T02:21:16","modified_gmt":"2026-05-13T00:21:16","slug":"danopol-hs-1-5-coverstrip","status":"publish","type":"product","link":"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/","title":{"rendered":"DANOPOL HS 1.5 COVERSTRIP"},"content":{"rendered":"<p>DANOPOL HS 1.5 COVERSTRIP es una l\u00e1mina sint\u00e9tica a base de PVC plastificado, fabricada mediante calandrado y reforzada con una armadura de malla de fibra de poli\u00e9ster. Esta l\u00e1mina es resistente a la intemperie y los rayos U.V.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Banda de PVC-p para puntos singulares.<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"family":[3073],"product_notice":[12157],"product_icon":[],"product_application":[10870,10876,10880,10898],"product_standards_certification":[12024,12025,12028,12029,12032,12033,12044,12055,12064],"product_benefits":[10187,10259,10260,10343,10356,10370,10477,10540,10573,10575],"product_support":[11919,11940,11953,11973,11974,11975],"product_substrate_preparation":[],"product_important_indications":[11243,11244,11262,11270,11274,11294,11311,11314,11325,11388,11428,11429,11430],"product_conservation":[11555,11563,11591,11595,11640,11641,11660,11718,11719,11721],"product_warning":[],"product_safety_hygiene":[],"system_certification":[],"product_maintenance":[],"product_safety_datasheet":[2695],"filter_special_uses":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u00e1mina sint\u00e9tica impermeabilizante cubiertas DANOPOL HS 1.5 Coverstrip<\/title>\n<meta name=\"description\" content=\"DANOPOL HS 1.5 Coverstrip es una l\u00e1mina sint\u00e9tica a base de PVC-p para impermeabilizaci\u00f3n de cubiertas fijadas mec\u00e1nicamente. Alto rendimiento. Danosa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00e1mina sint\u00e9tica impermeabilizante cubiertas DANOPOL HS 1.5 Coverstrip\" \/>\n<meta property=\"og:description\" content=\"DANOPOL HS 1.5 Coverstrip es una l\u00e1mina sint\u00e9tica a base de PVC-p para impermeabilizaci\u00f3n de cubiertas fijadas mec\u00e1nicamente. Alto rendimiento. Danosa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/\" \/>\n<meta property=\"og:site_name\" content=\"Danosa | Soluciones para la construcci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aislamientoeimpermeabilizacion\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T00:21:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DANOSA_SPAIN\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/#website\",\"url\":\"https:\/\/www.danosa.com\/es-es\/\",\"name\":\"Danosa | Soluciones para la construcci\u00f3n\",\"description\":\"Impermeabilizaci\u00f3n, aislamiento ac\u00fastico y t\u00e9rmico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.danosa.com\/es-es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/#webpage\",\"url\":\"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/\",\"name\":\"L\u00e1mina sint\u00e9tica impermeabilizante cubiertas DANOPOL HS 1.5 Coverstrip\",\"isPartOf\":{\"@id\":\"https:\/\/www.danosa.com\/es-es\/#website\"},\"datePublished\":\"2026-05-13T00:21:14+00:00\",\"dateModified\":\"2026-05-13T00:21:16+00:00\",\"description\":\"DANOPOL HS 1.5 Coverstrip es una l\u00e1mina sint\u00e9tica a base de PVC-p para impermeabilizaci\u00f3n de cubiertas fijadas mec\u00e1nicamente. Alto rendimiento. Danosa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.danosa.com\/es-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DANOPOL HS 1.5 COVERSTRIP\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00e1mina sint\u00e9tica impermeabilizante cubiertas DANOPOL HS 1.5 Coverstrip","description":"DANOPOL HS 1.5 Coverstrip es una l\u00e1mina sint\u00e9tica a base de PVC-p para impermeabilizaci\u00f3n de cubiertas fijadas mec\u00e1nicamente. Alto rendimiento. Danosa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/","og_locale":"es_ES","og_type":"article","og_title":"L\u00e1mina sint\u00e9tica impermeabilizante cubiertas DANOPOL HS 1.5 Coverstrip","og_description":"DANOPOL HS 1.5 Coverstrip es una l\u00e1mina sint\u00e9tica a base de PVC-p para impermeabilizaci\u00f3n de cubiertas fijadas mec\u00e1nicamente. Alto rendimiento. Danosa.","og_url":"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/","og_site_name":"Danosa | Soluciones para la construcci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/aislamientoeimpermeabilizacion\/","article_modified_time":"2026-05-13T00:21:16+00:00","twitter_card":"summary_large_image","twitter_site":"@DANOSA_SPAIN","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.danosa.com\/es-es\/#website","url":"https:\/\/www.danosa.com\/es-es\/","name":"Danosa | Soluciones para la construcci\u00f3n","description":"Impermeabilizaci\u00f3n, aislamiento ac\u00fastico y t\u00e9rmico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.danosa.com\/es-es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/#webpage","url":"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/","name":"L\u00e1mina sint\u00e9tica impermeabilizante cubiertas DANOPOL HS 1.5 Coverstrip","isPartOf":{"@id":"https:\/\/www.danosa.com\/es-es\/#website"},"datePublished":"2026-05-13T00:21:14+00:00","dateModified":"2026-05-13T00:21:16+00:00","description":"DANOPOL HS 1.5 Coverstrip es una l\u00e1mina sint\u00e9tica a base de PVC-p para impermeabilizaci\u00f3n de cubiertas fijadas mec\u00e1nicamente. Alto rendimiento. Danosa.","breadcrumb":{"@id":"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.danosa.com\/es-es\/producto\/danopol-hs-1-5-coverstrip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.danosa.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"DANOPOL HS 1.5 COVERSTRIP"}]}]}},"_links":{"self":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product\/3986"}],"collection":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/media?parent=3986"}],"wp:term":[{"taxonomy":"family","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/family?post=3986"},{"taxonomy":"product_notice","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_notice?post=3986"},{"taxonomy":"product_icon","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_icon?post=3986"},{"taxonomy":"product_application","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_application?post=3986"},{"taxonomy":"product_standards_certification","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_standards_certification?post=3986"},{"taxonomy":"product_benefits","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_benefits?post=3986"},{"taxonomy":"product_support","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_support?post=3986"},{"taxonomy":"product_substrate_preparation","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_substrate_preparation?post=3986"},{"taxonomy":"product_important_indications","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_important_indications?post=3986"},{"taxonomy":"product_conservation","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_conservation?post=3986"},{"taxonomy":"product_warning","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_warning?post=3986"},{"taxonomy":"product_safety_hygiene","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_safety_hygiene?post=3986"},{"taxonomy":"system_certification","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/system_certification?post=3986"},{"taxonomy":"product_maintenance","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_maintenance?post=3986"},{"taxonomy":"product_safety_datasheet","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_safety_datasheet?post=3986"},{"taxonomy":"filter_special_uses","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/filter_special_uses?post=3986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}