{"id":9837,"date":"2026-05-13T14:26:03","date_gmt":"2026-05-13T12:26:03","guid":{"rendered":"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/"},"modified":"2026-05-13T14:26:08","modified_gmt":"2026-05-13T12:26:08","slug":"danofelt-pp-90","status":"publish","type":"product","link":"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/","title":{"rendered":"DANOFELT PP 90"},"content":{"rendered":"<p>Geotextil no tejido formado por fibras virgenes, 100% polipropileno, unidos mec\u00e1nicamente por un proceso de agujeteado con posterior termofijado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geotextil de polipropileno<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"family":[3108],"product_notice":[12157],"product_icon":[],"product_application":[10790,11005],"product_standards_certification":[12044],"product_benefits":[10146,10292,10354,10369,10426,10477,10520],"product_support":[],"product_substrate_preparation":[],"product_important_indications":[11304,11311,11319,11402,11404,11406,11429,11438,11451],"product_conservation":[11533,11561,11563,11610,11718,11719,11721],"product_warning":[],"product_safety_hygiene":[],"system_certification":[],"product_maintenance":[],"product_safety_datasheet":[3458],"filter_special_uses":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Manta geotextil de polipropileno 100% | DANOFELT PP 90 | Danosa<\/title>\n<meta name=\"description\" content=\"DANOFELT es una manta geotextil de polipropileno para la protecci\u00f3n de las l\u00e1minas impermeabilizantes usadas en cubiertas planas y soleras. Danosa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manta geotextil de polipropileno 100% | DANOFELT PP 90 | Danosa\" \/>\n<meta property=\"og:description\" content=\"DANOFELT es una manta geotextil de polipropileno para la protecci\u00f3n de las l\u00e1minas impermeabilizantes usadas en cubiertas planas y soleras. Danosa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/\" \/>\n<meta property=\"og:site_name\" content=\"Danosa | Soluciones para la construcci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aislamientoeimpermeabilizacion\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T12:26:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DANOSA_SPAIN\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/#website\",\"url\":\"https:\/\/www.danosa.com\/es-es\/\",\"name\":\"Danosa | Soluciones para la construcci\u00f3n\",\"description\":\"Impermeabilizaci\u00f3n, aislamiento ac\u00fastico y t\u00e9rmico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.danosa.com\/es-es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/#webpage\",\"url\":\"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/\",\"name\":\"Manta geotextil de polipropileno 100% | DANOFELT PP 90 | Danosa\",\"isPartOf\":{\"@id\":\"https:\/\/www.danosa.com\/es-es\/#website\"},\"datePublished\":\"2026-05-13T12:26:03+00:00\",\"dateModified\":\"2026-05-13T12:26:08+00:00\",\"description\":\"DANOFELT es una manta geotextil de polipropileno para la protecci\u00f3n de las l\u00e1minas impermeabilizantes usadas en cubiertas planas y soleras. Danosa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.danosa.com\/es-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DANOFELT PP 90\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manta geotextil de polipropileno 100% | DANOFELT PP 90 | Danosa","description":"DANOFELT es una manta geotextil de polipropileno para la protecci\u00f3n de las l\u00e1minas impermeabilizantes usadas en cubiertas planas y soleras. Danosa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/","og_locale":"es_ES","og_type":"article","og_title":"Manta geotextil de polipropileno 100% | DANOFELT PP 90 | Danosa","og_description":"DANOFELT es una manta geotextil de polipropileno para la protecci\u00f3n de las l\u00e1minas impermeabilizantes usadas en cubiertas planas y soleras. Danosa.","og_url":"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/","og_site_name":"Danosa | Soluciones para la construcci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/aislamientoeimpermeabilizacion\/","article_modified_time":"2026-05-13T12:26:08+00:00","twitter_card":"summary_large_image","twitter_site":"@DANOSA_SPAIN","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.danosa.com\/es-es\/#website","url":"https:\/\/www.danosa.com\/es-es\/","name":"Danosa | Soluciones para la construcci\u00f3n","description":"Impermeabilizaci\u00f3n, aislamiento ac\u00fastico y t\u00e9rmico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.danosa.com\/es-es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/#webpage","url":"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/","name":"Manta geotextil de polipropileno 100% | DANOFELT PP 90 | Danosa","isPartOf":{"@id":"https:\/\/www.danosa.com\/es-es\/#website"},"datePublished":"2026-05-13T12:26:03+00:00","dateModified":"2026-05-13T12:26:08+00:00","description":"DANOFELT es una manta geotextil de polipropileno para la protecci\u00f3n de las l\u00e1minas impermeabilizantes usadas en cubiertas planas y soleras. Danosa.","breadcrumb":{"@id":"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.danosa.com\/es-es\/producto\/danofelt-pp-90\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.danosa.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"DANOFELT PP 90"}]}]}},"_links":{"self":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product\/9837"}],"collection":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/media?parent=9837"}],"wp:term":[{"taxonomy":"family","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/family?post=9837"},{"taxonomy":"product_notice","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_notice?post=9837"},{"taxonomy":"product_icon","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_icon?post=9837"},{"taxonomy":"product_application","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_application?post=9837"},{"taxonomy":"product_standards_certification","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_standards_certification?post=9837"},{"taxonomy":"product_benefits","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_benefits?post=9837"},{"taxonomy":"product_support","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_support?post=9837"},{"taxonomy":"product_substrate_preparation","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_substrate_preparation?post=9837"},{"taxonomy":"product_important_indications","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_important_indications?post=9837"},{"taxonomy":"product_conservation","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_conservation?post=9837"},{"taxonomy":"product_warning","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_warning?post=9837"},{"taxonomy":"product_safety_hygiene","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_safety_hygiene?post=9837"},{"taxonomy":"system_certification","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/system_certification?post=9837"},{"taxonomy":"product_maintenance","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_maintenance?post=9837"},{"taxonomy":"product_safety_datasheet","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/product_safety_datasheet?post=9837"},{"taxonomy":"filter_special_uses","embeddable":true,"href":"https:\/\/www.danosa.com\/es-es\/wp-json\/wp\/v2\/filter_special_uses?post=9837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}